{"id":1297,"date":"2025-09-05T08:09:18","date_gmt":"2025-09-05T08:09:18","guid":{"rendered":"https:\/\/jmtpressurejet.com\/?page_id=1297"},"modified":"2025-09-05T08:22:25","modified_gmt":"2025-09-05T08:22:25","slug":"jmt-3-high-pressure-plunger-water-pump","status":"publish","type":"page","link":"https:\/\/jmtpressurejet.com\/nl\/jmt-3-high-pressure-plunger-water-pump\/","title":{"rendered":"JMT-3 700bar hogedruk plunjer waterpomp"},"content":{"rendered":"<div>\n<div class=\"gb-element-2d1b0d70\">\n<div>\n<div class=\"gb-element-5deec3e5\">\n<div class=\"gb-element-e7fa051a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" class=\"gb-media-d066f1ab\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump.png\" title=\"jtm 3 hogedruk plunjer waterpomp\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jtm-3-high-pressure-plunger-water-pump-400x299.png 400w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\n<\/div>\n\n\n\n<div>\n<h5 class=\"gb-text\"><strong>JMT-3 700bar hogedruk plunjer waterpomp<\/strong><\/h5>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Model<\/td><td>JMT-3<\/td><\/tr><tr><td>Uitlaatdruk<\/td><td>700 bar\/14500psi<\/td><\/tr><tr><td>Waterstroomsnelheid<\/td><td>70 l\/min<\/td><\/tr><tr><td>Diameter zuiger<\/td><td>28 mm<\/td><\/tr><tr><td>Aantal plunjers<\/td><td>3<\/td><\/tr><tr><td>Invoersnelheid<\/td><td>1480r\/min<\/td><\/tr><tr><td>Pompsnelheid<\/td><td>366 omw\/min<\/td><\/tr><tr><td>Plunjerslag<\/td><td>120 mm<\/td><\/tr><tr><td>Motorvermogen<\/td><td>90 kW<\/td><\/tr><tr><td>Koelmethode<\/td><td>Waterkoeling<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-38c7d89c\">\n<div>\n<h2 class=\"gb-text gb-text-f63bc230\">Productkenmerken en -voordelen<\/h2>\n\n\n\n<p class=\"gb-text\">1. Geavanceerde technologie, compacte structuur en soepele en betrouwbare transmissie.<\/p>\n\n\n\n<p class=\"gb-text\">2. Stabiele en betrouwbare druk, eenvoudig instelbaar.<\/p>\n\n\n\n<p class=\"gb-text\">3. Roestvrij staal, schokbestendige siliconenolie en drukweergave.<\/p>\n\n\n\n<p class=\"gb-text\">4. Geforceerde smering aan de aandrijfzijde vermindert de wrijving en verbetert de smering, wat zorgt voor een soepele en betrouwbare transmissie.<\/p>\n\n\n\n<p class=\"gb-text\">5. Gesmede roestvrijstalen pompkop, stevig en duurzaam.<\/p>\n\n\n\n<p class=\"gb-text\">6. Synchrone koppeling zorgt voor een stabiele werking.<\/p>\n\n\n\n<p class=\"gb-text\">7. Hogedruk pomphuis van nodulair gietijzer; uitstekende warmteafvoer, harde textuur en bestand tegen vervorming.<\/p>\n\n\n\n<p class=\"gb-text\">8. De apparatuur is uitgerust met een filter om onzuiverheden in het binnenkomende water nauwkeurig te filteren, wat de levensduur van de waterpomp ten goede komt.<\/p>\n\n\n\n<p class=\"gb-text\">9. Verkrijgbaar met aandrijving door elektromotor of dieselmotor.<\/p>\n\n\n\n<p class=\"gb-text\">10. Het hydraulische uiteinde maakt gebruik van een geforceerd waterkoelsysteem om de plunjertemperatuur te koelen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-7326ebf7\">\n<div>\n<h2 class=\"gb-text gb-text-27a079f2\">Toepassingen Industrie<\/h2>\n\n\n\n<p>Het is geschikt voor waterinjectie in olievelden en mijnen, grote pijpleidingreiniging in de petrochemie, energiecentrales, gemeentelijke en andere industrie\u00ebn, omgekeerde osmose ontziltingssystemen, gesponnen niet-geweven stoffen, poedermetallurgie, enz.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-4bdcfc5d\">\n<div>\n<h2 class=\"gb-text gb-text-27ac96d1\">Gedetailleerde productspecificatie<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">Invoersnelheid (omw\/min)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">1480<\/td><td colspan=\"2\">Plunjerslag (mm)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"3\">95<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">Verminderingsratio (i)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">3.65<\/td><td colspan=\"2\">Pompsnelheid (omw\/min)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"3\">405<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">Vermogen (kW)<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td>37<\/td><td class=\"has-text-align-center\" data-align=\"center\">45<\/td><td>55<\/td><td>75<\/td><td>90<\/td><td>Diameter plunjer (mm)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">Nominale stroomsnelheid<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"6\" rowspan=\"2\">Nominale afvoerdruk (bar)<\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M\u00b3\/H<\/td><td class=\"has-text-align-center\" data-align=\"center\">L\/min<\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2.4<\/td><td class=\"has-text-align-center\" data-align=\"center\">40<\/td><td>370<\/td><td class=\"has-text-align-center\" data-align=\"center\">460<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td>22<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">50<\/td><td>300<\/td><td class=\"has-text-align-center\" data-align=\"center\">360<\/td><td>450<\/td><td><\/td><td><\/td><td><\/td><td>24<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3.9<\/td><td class=\"has-text-align-center\" data-align=\"center\">65<\/td><td>230<\/td><td class=\"has-text-align-center\" data-align=\"center\">280<\/td><td>350<\/td><td>500<\/td><td><\/td><td><\/td><td>26<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">4.5<\/td><td class=\"has-text-align-center\" data-align=\"center\">75<\/td><td>200<\/td><td class=\"has-text-align-center\" data-align=\"center\">250<\/td><td>300<\/td><td>380<\/td><td>500<\/td><td><\/td><td>28<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">5.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">85<\/td><td>170<\/td><td class=\"has-text-align-center\" data-align=\"center\">220<\/td><td>260<\/td><td>340<\/td><td>450<\/td><td>500<\/td><td>30<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">6.12<\/td><td class=\"has-text-align-center\" data-align=\"center\">102<\/td><td>150<\/td><td class=\"has-text-align-center\" data-align=\"center\">180<\/td><td>220<\/td><td>280<\/td><td>360<\/td><td>430<\/td><td>32<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">8.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">135<\/td><td>110<\/td><td class=\"has-text-align-center\" data-align=\"center\">140<\/td><td>170<\/td><td>210<\/td><td>280<\/td><td>330<\/td><td>35<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">10.2<\/td><td class=\"has-text-align-center\" data-align=\"center\">170<\/td><td>90<\/td><td class=\"has-text-align-center\" data-align=\"center\">110<\/td><td>140<\/td><td>170<\/td><td>240<\/td><td>280<\/td><td>40<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">12.9<\/td><td class=\"has-text-align-center\" data-align=\"center\">215<\/td><td>70<\/td><td class=\"has-text-align-center\" data-align=\"center\">90<\/td><td>110<\/td><td>130<\/td><td>180<\/td><td>200<\/td><td>45<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><td class=\"has-text-align-center\" data-align=\"center\">250<\/td><td>60<\/td><td class=\"has-text-align-center\" data-align=\"center\">70<\/td><td>90<\/td><td>120<\/td><td>160<\/td><td>190<\/td><td>50<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-b0a8c443\">\n<div>\n<h2 class=\"gb-text gb-text-3e5a6473\"> Toepassingsgevallen<\/h2>\n\n\n\n<div class=\"gb-element-47fc66a8\">\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-607d0539\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application9.jpg\" title=\"hogedrukreiniger toepassing9\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application9.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application9-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application9-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application9-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-da2ebe66\"><strong>Hogedruk waterinjectie via pijpleiding<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-726ec094\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application6.jpg\" title=\"hogedrukreiniger toepassing6\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application6.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application6-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application6-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application6-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-59f588a6\"><strong>Druktests van pijpleidingen<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-1d9bdcdb\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application4-1.jpg\" title=\"hogedrukreinigertoepassing4\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application4-1.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application4-1-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application4-1-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cleaner-application4-1-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-ce832980\"><strong>Rioolbuis schoonmaken<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8c8de760\">\n<div class=\"gb-element-fc1e320d\">\n<div>\n<h2 class=\"gb-text gb-text-8163a5d9\">Populaire producten<\/h2>\n\n\n<div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-345\" style=\"--carousel-slider-nav-color:rgb(30,115,190);--carousel-slider-active-nav-color:rgba(0,137,225,0.82);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-345\" class=\"carousel-slider carousel-slider-345 arrows-visibility-hover dots-visibility-always arrows-outside dots-center dots-square owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":true,\"slideBy\":4,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":4000,\"autoplaySpeed\":5000,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":3},\"576\":{\"items\":4},\"768\":{\"items\":4},\"1024\":{\"items\":4},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-cooling-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedruk koelwaterpomp\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/jmt-2-high-pressure-grouting-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/High-pressure-jet-grouting-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedruk voegmachine<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-pipe-dredging-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedrukrioolrioolreiniger<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedrukreinigers<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-test-pump-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-test-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedruktestpomp<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-concrete-roughening-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedruk Beton Opruwen Machine<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-water-accessory-actuator\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Extra aandrijving<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-plunger-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Hogedruk plunjerwaterpomp<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-presure-water-jet-cutting-machine\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Waterstraalsnijmachine\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/automatic-high-pressure-cleaning-system\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Automatisch reinigingssysteem<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/airport-runway-glue-removal-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">https:\/\/jmtpressurejet.com\/airport-runway-glue-removal-equipment\/<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/hot-water-high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Warm water hogedrukreinigingsapparatuur\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/high-pressure-water-road-marking-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/\u56fe\u72471-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Apparatuur voor het verwijderen van wegmarkeringen\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/nl\/water-jet-cutting-and-blasting-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Waterstraalsnijden en -stralen\n<\/p><\/div><\/a><\/div>\n\n<\/div><!-- .carousel-slider-345 -->\n<\/div><!-- .carousel-slider-outer-345 -->\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-279faa38\">\n<div>\n<div class=\"gb-element-f30a2a07\">\n<div>\n<h2 class=\"gb-text gb-text-90c18544\">Neem contact met ons op<\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"7\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/1297#wpcf7-f7-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/nl\/wp-json\/wp\/v2\/pages\/1297#wpcf7-f7-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Naam*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefoon*\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Snelle tips voor een snelle en nauwkeurige offerte*: 1. Welke apparatuur moet u kopen? 2. Wat is uw primaire toepassing\/industrie? 3. Wat is uw vereiste voor druk\/debiet?\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Stuur  in\" \/>\n<\/p><input type=\"hidden\" id=\"ct_checkjs_cf7_b6d767d2f8ed5d21a44b0e5886680cb9\" name=\"ct_checkjs_cf7\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_cf7_b6d767d2f8ed5d21a44b0e5886680cb9\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, '1499353dbb4dcd643962149a0691e276cd27b79cebd88e665d0884a7f539b423');}}, 1000);<\/script><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"nl\"\/><\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>JMT-3 700bar High Pressure Plunger Water Pump Model JMT-3 Outlet Pressure 700bar\/14500psi Water Flow Rate 70L\/min Plunger Diameter 28mm Number of Plungers 3 Input Speed 1480r\/min Pump Speed 366r\/min Plunger Stroke 120mm Engine Power 90kw Cooling Method Water Cooling Product Features and Advantages 1. Advanced technology, compact structure, and smooth and reliable transmission. 2. Stable &#8230; <a title=\"JMT-3 700bar hogedruk plunjer waterpomp\" class=\"read-more\" href=\"https:\/\/jmtpressurejet.com\/nl\/jmt-3-high-pressure-plunger-water-pump\/\" aria-label=\"Lees meer over JMT-3 700bar High Pressure Plunger Water Pump\">Meer lezen<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1297","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/pages\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/comments?post=1297"}],"version-history":[{"count":3,"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/pages\/1297\/revisions"}],"predecessor-version":[{"id":1324,"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/pages\/1297\/revisions\/1324"}],"wp:attachment":[{"href":"https:\/\/jmtpressurejet.com\/nl\/wp-json\/wp\/v2\/media?parent=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}