{"id":793,"date":"2025-08-21T02:46:44","date_gmt":"2025-08-21T02:46:44","guid":{"rendered":"https:\/\/jmtpressurejet.com\/?page_id=793"},"modified":"2025-09-12T08:35:26","modified_gmt":"2025-09-12T08:35:26","slug":"jmt-2-180-bar-fixed-pipe-dredging-machine","status":"publish","type":"page","link":"https:\/\/jmtpressurejet.com\/ja\/jmt-2-180-bar-fixed-pipe-dredging-machine\/","title":{"rendered":"JMT-2-180\u30d0\u30fc\u56fa\u5b9a\u30d1\u30a4\u30d7\u6d5a\u6e2b\u6a5f"},"content":{"rendered":"<div>\n<div class=\"gb-element-2d1b0d70\">\n<div>\n<div class=\"gb-element-5deec3e5\">\n<div class=\"gb-element-e7fa051a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" class=\"gb-media-d066f1ab\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/JMT-2-180-Bar-Fixed-Sewer-Drain-Machine-equipment1.png\" title=\"JMT-2-180\u30d0\u30fc\u56fa\u5b9a\u5f0f\u4e0b\u6c34\u9053\u6392\u6c34\u6a5f\u8a2d\u50991\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/JMT-2-180-Bar-Fixed-Sewer-Drain-Machine-equipment1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/JMT-2-180-Bar-Fixed-Sewer-Drain-Machine-equipment1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/JMT-2-180-Bar-Fixed-Sewer-Drain-Machine-equipment1-16x12.png 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\n<\/div>\n\n\n\n<div>\n<h5 class=\"gb-text\"><strong>JMT-2-180\u30d0\u30fc\u56fa\u5b9a\u30d1\u30a4\u30d7\u6d5a\u6e2b\u6a5f<\/strong><\/h5>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\u30e2\u30c7\u30eb<\/td><td>JMT-2<\/td><\/tr><tr><td>\u51fa\u53e3\u5727\u529b<\/td><td>180bar\/2600psi<\/td><\/tr><tr><td>\u6c34\u6d41\u91cf<\/td><td>135L\/\u5206<\/td><\/tr><tr><td>\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u5f84<\/td><td>50mm<\/td><\/tr><tr><td>\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u6570<\/td><td>3<\/td><\/tr><tr><td>\u5165\u529b\u901f\u5ea6<\/td><td>1480r\/\u5206<\/td><\/tr><tr><td>\u30dd\u30f3\u30d7\u901f\u5ea6<\/td><td>1450r\/\u5206<\/td><\/tr><tr><td>\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u30b9\u30c8\u30ed\u30fc\u30af<\/td><td>28mm<\/td><\/tr><tr><td>\u30a8\u30f3\u30b8\u30f3\u30d1\u30ef\u30fc<\/td><td>62kw\/85HP<\/td><\/tr><tr><td>\u6c34\u5165\u53e3\u30b5\u30a4\u30ba<\/td><td>G2\u30a4\u30f3\u30c1<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-be47f15e\">\n<div>\n<h2 class=\"gb-text gb-text-f640b470\">\u52d5\u4f5c\u539f\u7406<\/h2>\n\n\n\n<p>\u9ad8\u5727\u30dd\u30f3\u30d7\u3067\u9ad8\u5727\u30b8\u30a7\u30c3\u30c8\u6c34\u3092\u767a\u751f\u3055\u305b\u307e\u3059\u3002\u8a70\u307e\u308a\u9664\u53bb\u30ce\u30ba\u30eb\u3092\u9ad8\u5727\u30db\u30fc\u30b9\u3067\u30dd\u30f3\u30d7\u306b\u63a5\u7d9a\u3057\u3001\u30ce\u30ba\u30eb\u3092\u8a70\u307e\u308a\u3092\u9664\u53bb\u3059\u308b\u30d1\u30a4\u30d7\u5185\u306b\u76f4\u63a5\u8a2d\u7f6e\u3057\u307e\u3059\u3002 <\/p>\n\n\n\n<p>\u9ad8\u5727\u30dd\u30f3\u30d7\u304c\u4f5c\u52d5\u3059\u308b\u3068\u3001\u30ce\u30ba\u30eb\u5f8c\u65b9\u304b\u3089\u5674\u51fa\u3059\u308b\u9ad8\u5727\u6c34\u306e\u53cd\u529b\u3067\u30ce\u30ba\u30eb\u304c\u4e00\u6c17\u306b\u524d\u65b9\u3078\u62bc\u3057\u51fa\u3055\u308c\u307e\u3059\u3002\u30ce\u30ba\u30eb\u306e\u524d\u5f8c\u306e\u30ce\u30ba\u30eb\u5b54\u304b\u3089\u767a\u751f\u3059\u308b\u9ad8\u5727\u30b8\u30a7\u30c3\u30c8\u6c34\u6d41\u304c\u914d\u7ba1\u5185\u3092\u7d20\u65e9\u304f\u6d17\u6d44\u3002 <\/p>\n\n\n\n<p>\u30d1\u30a4\u30d7\u30b3\u30ec\u30af\u30bf\u30fc\u304c\u30ce\u30ba\u30eb\u3092\u5f15\u304d\u623b\u3059\u3068\u3001\u9ad8\u5727\u6c34\u6d41\u304c\u30d1\u30a4\u30d7\u675f\u306e\u6c5a\u308c\u3092\u6d17\u3044\u6d41\u3059\u3002 <\/p>\n\n\n\n<p>\u7528\u9014\u81ea\u6cbb\u4f53\u3001\u4f4f\u5b85\u3001\u5de5\u696d\u56e3\u5730\u3067\u306e\u30d1\u30a4\u30d7\u306e\u8a70\u307e\u308a\u9664\u53bb\u3084\u6e05\u6383\u306b\u4f7f\u7528\u3002<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-38c7d89c\">\n<div>\n<h2 class=\"gb-text gb-text-f63bc230\">\u88fd\u54c1\u306e\u7279\u5fb4\u3068\u5229\u70b9<\/h2>\n\n\n\n<p class=\"gb-text\">1.\u9ad8\u5ea6\u306a\u6280\u8853\u3001\u30b3\u30f3\u30d1\u30af\u30c8\u306a\u69cb\u9020\u3001\u6ed1\u3089\u304b\u3067\u4fe1\u983c\u6027\u306e\u9ad8\u3044\u4f1d\u9001\u3002<\/p>\n\n\n\n<p class=\"gb-text\">2.\u5b89\u5b9a\u3057\u305f\u4fe1\u983c\u3067\u304d\u308b\u5727\u529b\u3001\u5bb9\u6613\u306a\u8abf\u7bc0\u3002<\/p>\n\n\n\n<p class=\"gb-text\">3.\u30b9\u30c6\u30f3\u30ec\u30b9\u30b9\u30c1\u30fc\u30eb\u3001\u8010\u885d\u6483\u30b7\u30ea\u30b3\u30f3\u30aa\u30a4\u30eb\u3001\u5727\u529b\u8868\u793a\u3002<\/p>\n\n\n\n<p class=\"gb-text\">4.\u30d1\u30ef\u30fc\u30a8\u30f3\u30c9\u306e\u5f37\u5236\u6f64\u6ed1\u306f\u3001\u6469\u64e6\u3092\u4f4e\u6e1b\u3057\u3001\u6f64\u6ed1\u6027\u3092\u5411\u4e0a\u3055\u305b\u3001\u30b9\u30e0\u30fc\u30ba\u3067\u4fe1\u983c\u6027\u306e\u9ad8\u3044\u4f1d\u9054\u3092\u4fdd\u8a3c\u3057\u307e\u3059\u3002<\/p>\n\n\n\n<p class=\"gb-text\">5.\u935b\u9020\u30b9\u30c6\u30f3\u30ec\u30b9\u92fc\u30dd\u30f3\u30d7\u30d8\u30c3\u30c9\u3001\u9811\u4e08\u3067\u8010\u4e45\u6027\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n\n\n\n<p class=\"gb-text\">6.\u540c\u671f\u30ab\u30c3\u30d7\u30ea\u30f3\u30b0\u306b\u3088\u308a\u5b89\u5b9a\u3057\u305f\u52d5\u4f5c\u3092\u5b9f\u73fe\u3002<\/p>\n\n\n\n<p class=\"gb-text\">7.\u9ad8\u5727\u30dd\u30f3\u30d7\u30cf\u30a6\u30b8\u30f3\u30b0\u306f\u30c0\u30af\u30bf\u30a4\u30eb\u92f3\u9244\u88fd\u3067\u3001\u653e\u71b1\u6027\u306b\u512a\u308c\u3001\u786c\u8cea\u3067\u5909\u5f62\u3057\u306b\u304f\u3044\u3002<\/p>\n\n\n\n<p class=\"gb-text\">8.\u88c5\u7f6e\u306b\u306f\u30d5\u30a3\u30eb\u30bf\u30fc\u304c\u88c5\u5099\u3055\u308c\u3066\u304a\u308a\u3001\u6d41\u5165\u6c34\u4e2d\u306e\u4e0d\u7d14\u7269\u3092\u7684\u78ba\u306b\u308d\u904e\u3059\u308b\u3002<\/p>\n\n\n\n<p class=\"gb-text\">9.\u96fb\u6c17\u30e2\u30fc\u30bf\u30fc\u307e\u305f\u306f\u30c7\u30a3\u30fc\u30bc\u30eb\u30a8\u30f3\u30b8\u30f3\u99c6\u52d5\u306e\u3044\u305a\u308c\u3067\u3082\u5229\u7528\u53ef\u80fd\u3002<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-7326ebf7\">\n<div>\n<h2 class=\"gb-text gb-text-27a079f2\">\u5fdc\u7528\u7523\u696d<\/h2>\n\n\n\n<p class=\"gb-text\">1.\u4f4f\u5b85\u7528\u30d1\u30a4\u30d7\u6d17\u6d44\u3092\u542b\u3080\u3001\u591a\u7528\u9014\u306e\u6d17\u6d44\u3002<\/p>\n\n\n\n<p class=\"gb-text\">2.\u81ea\u6cbb\u4f53\u306e\u30d1\u30a4\u30d7\u6d17\u6d44\u3084\u8a70\u307e\u308a\u9664\u53bb\u306a\u3069\u3001\u591a\u7528\u9014\u306e\u6d17\u6d44\u3002<\/p>\n\n\n\n<p class=\"gb-text\">3.\u8fc2\u56de\u30c8\u30f3\u30cd\u30eb\u7ba1\u6d17\u6d44\u3092\u542b\u3080\u591a\u7528\u9014\u6d17\u6d44\u3002<\/p>\n\n\n\n<p class=\"gb-text\">4.\u30c8\u30f3\u30cd\u30eb\u3084\u6697\u6e20\u7ba1\u306e\u6d17\u6d44\u3092\u542b\u3080\u3001\u591a\u7528\u9014\u306e\u6d17\u6d44\u3002<\/p>\n\n\n\n<p class=\"gb-text\">5.\u8239\u5e95\u306e\u8239\u4f53\u6d17\u6d44\u3001\u7532\u677f\u6d17\u6d44\u3001\u6c5a\u67d3\u9664\u53bb\u3001\u6d77\u6d0b\u751f\u7269\u306e\u9664\u53bb\u3002<\/p>\n\n\n\n<p class=\"gb-text\">6.\u51b6\u91d1\u8a2d\u5099\u3068\u51b6\u91d1\u9727\u5316\u3002<\/p>\n\n\n\n<p class=\"gb-text\">7.\u5bb9\u5668\uff0f\u30d1\u30a4\u30d7\u30e9\u30a4\u30f3\uff0f\u9306\uff0f\u30b9\u30b1\u30fc\u30eb\u6d17\u6d44\u3092\u542b\u3080\u6a5f\u68b0\u88fd\u9020\u5de5\u5834\u3002<\/p>\n\n\n\n<p class=\"gb-text\">8.\u30bb\u30e1\u30f3\u30c8\u5de5\u5834\u306e\u914d\u7ba1\u6e05\u6383\u3001\u8a2d\u5099\u8868\u9762\u306e\u6cb9\u8102\u3084\u6c5a\u308c\u306e\u9664\u53bb\u3002<\/p>\n\n\n\n<p class=\"gb-text\">9.\u9271\u696d\u7528\u6cb9\u5727\u30b5\u30dd\u30fc\u30c8\u306e\u6d17\u6d44\u3001\u518d\u88fd\u9020\u306a\u3069<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-4bdcfc5d\">\n<div>\n<h2 class=\"gb-text gb-text-27ac96d1\">\u88fd\u54c1\u4ed5\u69d8\u8a73\u7d30<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">\u5165\u529b\u901f\u5ea6 (r\/min)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">1480<\/td><td colspan=\"2\">\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u30b9\u30c8\u30ed\u30fc\u30af\uff08mm\uff09<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"3\">95<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">\u524a\u6e1b\u7387 (i)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">3.65<\/td><td colspan=\"2\">\u30dd\u30f3\u30d7\u901f\u5ea6 (r\/min)<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"3\">1405<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">\u51fa\u529b\uff08kw\uff09<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td>37<\/td><td class=\"has-text-align-center\" data-align=\"center\">45<\/td><td>55<\/td><td>75<\/td><td>90<\/td><td>\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u5f84\uff08mm\uff09<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">\u5b9a\u683c\u6d41\u91cf<\/td><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"6\" rowspan=\"2\">\u5b9a\u683c\u5410\u51fa\u5727\u529b (Bar)<\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M\u00b3\/H<\/td><td class=\"has-text-align-center\" data-align=\"center\">L\/\u5206<\/td><td><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2.4<\/td><td class=\"has-text-align-center\" data-align=\"center\">40<\/td><td>370<\/td><td class=\"has-text-align-center\" data-align=\"center\">460<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td>22<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">50<\/td><td>300<\/td><td class=\"has-text-align-center\" data-align=\"center\">360<\/td><td>450<\/td><td><\/td><td><\/td><td><\/td><td>24<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3.9<\/td><td class=\"has-text-align-center\" data-align=\"center\">65<\/td><td>230<\/td><td class=\"has-text-align-center\" data-align=\"center\">280<\/td><td>350<\/td><td>500<\/td><td><\/td><td><\/td><td>26<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">4.5<\/td><td class=\"has-text-align-center\" data-align=\"center\">75<\/td><td>200<\/td><td class=\"has-text-align-center\" data-align=\"center\">250<\/td><td>300<\/td><td>380<\/td><td>500<\/td><td><\/td><td>28<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">5.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">85<\/td><td>170<\/td><td class=\"has-text-align-center\" data-align=\"center\">220<\/td><td>260<\/td><td>340<\/td><td>450<\/td><td>500<\/td><td>30<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">6.12<\/td><td class=\"has-text-align-center\" data-align=\"center\">102<\/td><td>150<\/td><td class=\"has-text-align-center\" data-align=\"center\">180<\/td><td>220<\/td><td>280<\/td><td>360<\/td><td>430<\/td><td>32<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">8.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">135<\/td><td>110<\/td><td class=\"has-text-align-center\" data-align=\"center\">140<\/td><td>170<\/td><td>210<\/td><td>280<\/td><td>330<\/td><td>35<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">10.2<\/td><td class=\"has-text-align-center\" data-align=\"center\">170<\/td><td>90<\/td><td class=\"has-text-align-center\" data-align=\"center\">110<\/td><td>140<\/td><td>170<\/td><td>240<\/td><td>280<\/td><td>40<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">12.9<\/td><td class=\"has-text-align-center\" data-align=\"center\">215<\/td><td>70<\/td><td class=\"has-text-align-center\" data-align=\"center\">90<\/td><td>110<\/td><td>130<\/td><td>180<\/td><td>200<\/td><td>45<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><td class=\"has-text-align-center\" data-align=\"center\">250<\/td><td>60<\/td><td class=\"has-text-align-center\" data-align=\"center\">70<\/td><td>90<\/td><td>120<\/td><td>160<\/td><td>190<\/td><td>50<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-b0a8c443\">\n<div>\n<h2 class=\"gb-text gb-text-3e5a6473\"> \u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u4e8b\u4f8b<\/h2>\n\n\n\n<div class=\"gb-element-47fc66a8\">\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-607d0539\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5.jpg\" title=\"\u9ad8\u5727\u6d17\u6d44\u6a5f\u306e\u7528\u90141\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-da2ebe66\"><strong>\u30bb\u30e1\u30f3\u30c8\u7ba1\u6d17\u6d44<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-726ec094\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4.jpg\" title=\"\u9ad8\u5727\u6d17\u6d44\u6a5f\u306e\u7528\u90142\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-59f588a6\"><strong>\u4e0b\u6c34\u7ba1\u6e05\u6383<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-1d9bdcdb\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4.jpg\" title=\"\u9ad8\u5727\u6d17\u6d44\u6a5f\u306e\u7528\u90143\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-ce832980\"><strong>\u56db\u89d2\u3044\u6e9d\u306e\u6e05\u6383<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8c8de760\">\n<div class=\"gb-element-fc1e320d\">\n<div>\n<h2 class=\"gb-text gb-text-8163a5d9\">\u58f2\u308c\u7b4b\u5546\u54c1<\/h2>\n\n\n<div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-345\" style=\"--carousel-slider-nav-color:rgb(30,115,190);--carousel-slider-active-nav-color:rgba(0,137,225,0.82);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-345\" class=\"carousel-slider carousel-slider-345 arrows-visibility-hover dots-visibility-always arrows-outside dots-center dots-square owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":true,\"slideBy\":4,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":4000,\"autoplaySpeed\":5000,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":3},\"576\":{\"items\":4},\"768\":{\"items\":4},\"1024\":{\"items\":4},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/hot-water-high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u6e29\u6c34\u9ad8\u5727\u6d17\u6d44\u6a5f\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-pipe-dredging-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u4e0b\u6c34\u9053\u30c9\u30ec\u30f3\u30af\u30ea\u30fc\u30ca\u30fc<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-water-accessory-actuator\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u30a2\u30af\u30bb\u30b5\u30ea\u30fb\u30a2\u30af\u30c1\u30e5\u30a8\u30fc\u30bf<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-cooling-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u51b7\u5374\u6c34\u30dd\u30f3\u30d7\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u6d17\u6d44\u6a5f<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-water-road-marking-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/\u56fe\u72471-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9053\u8def\u6a19\u8b58\u9664\u53bb\u88c5\u7f6e\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-test-pump-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-test-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u30c6\u30b9\u30c8\u30dd\u30f3\u30d7<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-plunger-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u30d7\u30e9\u30f3\u30b8\u30e3\u30fc\u6c34\u30dd\u30f3\u30d7<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/water-jet-cutting-and-blasting-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u30a6\u30a9\u30fc\u30bf\u30fc\u30b8\u30a7\u30c3\u30c8\u5207\u65ad\u304a\u3088\u3073\u30d6\u30e9\u30b9\u30c8\u88c5\u7f6e\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/airport-runway-glue-removal-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">https:\/\/jmtpressurejet.com\/airport-runway-glue-removal-equipment\/<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-pressure-concrete-roughening-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u30b3\u30f3\u30af\u30ea\u30fc\u30c8\u7c97\u9762\u5316\u6a5f<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/jmt-2-high-pressure-grouting-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/High-pressure-jet-grouting-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u9ad8\u5727\u30b0\u30e9\u30a6\u30c6\u30a3\u30f3\u30b0\u30de\u30b7\u30f3<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/high-presure-water-jet-cutting-machine\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u30a6\u30a9\u30fc\u30bf\u30fc\u30b8\u30a7\u30c3\u30c8\u5207\u65ad\u6a5f\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/ja\/automatic-high-pressure-cleaning-system\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u81ea\u52d5\u6d17\u6d44\u30b7\u30b9\u30c6\u30e0<\/p><\/div><\/a><\/div>\n\n<\/div><!-- .carousel-slider-345 -->\n<\/div><!-- .carousel-slider-outer-345 -->\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-279faa38\">\n<div>\n<div class=\"gb-element-f30a2a07\">\n<div>\n<h2 class=\"gb-text gb-text-90c18544\">\u304a\u554f\u3044\u5408\u308f\u305b<\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"7\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ja\/wp-json\/wp\/v2\/pages\/793#wpcf7-f7-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u304a\u554f\u3044\u5408\u308f\u305b\u30d5\u30a9\u30fc\u30e0\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ja\/wp-json\/wp\/v2\/pages\/793#wpcf7-f7-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u540d\u524d\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E\u30e1\u30fc\u30eb\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u96fb\u8a71\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u8fc5\u901f\u3067\u6b63\u78ba\u306a\u898b\u7a4d\u3082\u308a\u306e\u305f\u3081\u306e\u30d2\u30f3\u30c8*\uff1a1.2.\u4e3b\u306a\u7528\u9014\/\u7523\u696d\u306f\u4f55\u3067\u3059\u304b\uff1f3.\u5727\u529b\/\u6d41\u91cf\u306e\u8981\u4ef6\u306f\u4f55\u3067\u3059\u304b\uff1f\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u6295\u7a3f\u3059\u308b\" \/>\n<\/p><input type=\"hidden\" id=\"ct_checkjs_cf7_70efdf2ec9b086079795c442636b55fb\" name=\"ct_checkjs_cf7\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_cf7_70efdf2ec9b086079795c442636b55fb\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, '1499353dbb4dcd643962149a0691e276cd27b79cebd88e665d0884a7f539b423');}}, 1000);<\/script><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ja\"\/><\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>JMT-2-180 Bar Fixed Pipe Dredging Machine Model JMT-2 Outlet Pressure 180bar\/2600psi Water Flow Rate 135L\/min Plunger Diameter 50mm Number of Plungers 3 Input Speed 1480r\/min Pump Speed 1450r\/min Plunger Stroke 28mm Engine Power 62kw\/85HP Water Inlet Size G2-inch Working Principles The high-pressure pump generates a high-pressure water jet. Connect the pipe unclogging nozzle to the &#8230; <a title=\"JMT-2-180\u30d0\u30fc\u56fa\u5b9a\u30d1\u30a4\u30d7\u6d5a\u6e2b\u6a5f\" class=\"read-more\" href=\"https:\/\/jmtpressurejet.com\/ja\/jmt-2-180-bar-fixed-pipe-dredging-machine\/\" aria-label=\"JMT-2-180 Bar Fixed Pipe Dredging Machine \u306b\u3064\u3044\u3066\u3055\u3089\u306b\u8aad\u3080\">\u3082\u3063\u3068\u8aad\u3080<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-793","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/pages\/793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/comments?post=793"}],"version-history":[{"count":7,"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/pages\/793\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/pages\/793\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/jmtpressurejet.com\/ja\/wp-json\/wp\/v2\/media?parent=793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}