{"id":784,"date":"2025-08-20T09:59:12","date_gmt":"2025-08-20T09:59:12","guid":{"rendered":"https:\/\/jmtpressurejet.com\/?page_id=784"},"modified":"2025-09-12T08:34:50","modified_gmt":"2025-09-12T08:34:50","slug":"jmt-1-180bar-motor-driven-pipe-dredging-machine","status":"publish","type":"page","link":"https:\/\/jmtpressurejet.com\/fr\/jmt-1-180bar-motor-driven-pipe-dredging-machine\/","title":{"rendered":"JMT-1-180BAR motor driven pipe dredging machine"},"content":{"rendered":"<div>\n<div class=\"gb-element-2d1b0d70\">\n<div>\n<div class=\"gb-element-5deec3e5\">\n<div class=\"gb-element-e7fa051a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" class=\"gb-media-d066f1ab\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jiematt-high-pressure-waterjet-pipeline-equipment3.jpg\" title=\"\u00c9quipement de canalisation \u00e0 jet d&#039;eau haute pression jiematt3\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jiematt-high-pressure-waterjet-pipeline-equipment3.jpg 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jiematt-high-pressure-waterjet-pipeline-equipment3-300x225.jpg 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/jiematt-high-pressure-waterjet-pipeline-equipment3-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\n<\/div>\n\n\n\n<div>\n<h5 class=\"gb-text\"><strong>JMT-1-180BAR Moteur <strong>Drain d'\u00e9gout<\/strong> <strong>Machine de nettoyage<\/strong><\/strong><\/h5>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Mod\u00e8le<\/td><td>JMT-1<\/td><\/tr><tr><td>Pression de sortie<\/td><td>180bar\/2600psi<\/td><\/tr><tr><td>D\u00e9bit d'eau<\/td><td>55L\/min<\/td><\/tr><tr><td>Diam\u00e8tre du piston<\/td><td>28 mm<\/td><\/tr><tr><td>Nombre de poussoirs<\/td><td>3<\/td><\/tr><tr><td>Vitesse d'entr\u00e9e<\/td><td>3600r\/min<\/td><\/tr><tr><td>Vitesse de la pompe<\/td><td>1450r\/min<\/td><\/tr><tr><td>Course du piston<\/td><td>21mm<\/td><\/tr><tr><td>Puissance du moteur<\/td><td>15KW<\/td><\/tr><tr><td>Taille de l'entr\u00e9e d'eau<\/td><td>1,5 pouce<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-be47f15e\">\n<div>\n<h2 class=\"gb-text gb-text-f640b470\">Principes de travail<\/h2>\n\n\n\n<p>La pompe haute pression g\u00e9n\u00e8re un jet d'eau \u00e0 haute pression. Raccorder la buse de d\u00e9bouchage \u00e0 la pompe via un tuyau haute pression et placer la buse directement \u00e0 l'int\u00e9rieur de la canalisation \u00e0 d\u00e9boucher. <\/p>\n\n\n\n<p>Lorsque la pompe \u00e0 haute pression fonctionne, la force de r\u00e9action g\u00e9n\u00e9r\u00e9e par l'eau \u00e0 haute pression \u00e9ject\u00e9e \u00e0 l'arri\u00e8re de la buse pousse rapidement cette derni\u00e8re vers l'avant. Les jets d'eau haute pression g\u00e9n\u00e9r\u00e9s par les orifices avant et arri\u00e8re de la buse nettoient rapidement le tuyau. <\/p>\n\n\n\n<p>Lorsque le ramasseur de tuyaux tire la buse vers l'arri\u00e8re, le flux d'eau \u00e0 haute pression chasse la salet\u00e9 du faisceau de tuyaux. <\/p>\n\n\n\n<p>Applications : Utilis\u00e9 pour d\u00e9boucher et d\u00e9gager les canalisations obstru\u00e9es dans les parcs municipaux, r\u00e9sidentiels et industriels.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-38c7d89c\">\n<div>\n<h2 class=\"gb-text gb-text-f63bc230\">Caract\u00e9ristiques et avantages du produit<\/h2>\n\n\n\n<p class=\"gb-text\">1. Technologie avanc\u00e9e, structure compacte, transmission souple et fiable.<\/p>\n\n\n\n<p class=\"gb-text\">2. Pression stable et fiable, r\u00e9glage facile.<\/p>\n\n\n\n<p class=\"gb-text\">3. Acier inoxydable, huile de silicone r\u00e9sistante aux chocs et affichage de la pression.<\/p>\n\n\n\n<p class=\"gb-text\">4. La lubrification forc\u00e9e de la partie motrice r\u00e9duit les frottements et am\u00e9liore le pouvoir lubrifiant, ce qui garantit une transmission souple et fiable.<\/p>\n\n\n\n<p class=\"gb-text\">5. T\u00eate de pompe en acier inoxydable forg\u00e9, robuste et durable.<\/p>\n\n\n\n<p class=\"gb-text\">6. L'accouplement synchrone assure un fonctionnement stable.<\/p>\n\n\n\n<p class=\"gb-text\">7. Le corps de la pompe haute pression est en fonte ductile ; excellente dissipation de la chaleur, texture dure et r\u00e9sistante \u00e0 la d\u00e9formation.<\/p>\n\n\n\n<p class=\"gb-text\">8. L'\u00e9quipement est \u00e9quip\u00e9 d'un filtre qui filtre avec pr\u00e9cision les impuret\u00e9s pr\u00e9sentes dans l'eau entrante, ce qui permet de prolonger la dur\u00e9e de vie de la pompe \u00e0 eau.<\/p>\n\n\n\n<p class=\"gb-text\">9. Disponible avec un moteur \u00e9lectrique ou un moteur diesel.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-7326ebf7\">\n<div>\n<h2 class=\"gb-text gb-text-27a079f2\">Applications Industrie<\/h2>\n\n\n\n<p class=\"gb-text\">1. Nettoyage multi-applications, y compris le nettoyage des canalisations des propri\u00e9t\u00e9s r\u00e9sidentielles.<\/p>\n\n\n\n<p class=\"gb-text\">2. Nettoyage multi-application, y compris le nettoyage et le d\u00e9bouchage des canalisations municipales.<\/p>\n\n\n\n<p class=\"gb-text\">3. Nettoyage multi-applications, y compris le nettoyage des conduites des tunnels de d\u00e9rivation.<\/p>\n\n\n\n<p class=\"gb-text\">4. Nettoyage multi-applications, y compris le nettoyage des tunnels et des canalisations.<\/p>\n\n\n\n<p class=\"gb-text\">5. Nettoyage de la coque, nettoyage du pont, d\u00e9contamination et \u00e9limination de la v\u00e9g\u00e9tation marine du fond des navires.<\/p>\n\n\n\n<p class=\"gb-text\">6. \u00c9quipement m\u00e9tallurgique et atomisation m\u00e9tallurgique.<\/p>\n\n\n\n<p class=\"gb-text\">7. Usines de fabrication de machines, y compris le nettoyage des cuves, des tuyauteries, de la rouille et du calcaire.<\/p>\n\n\n\n<p class=\"gb-text\">8. Nettoyage des tuyaux de la cimenterie, \u00e9limination de la graisse et de la salet\u00e9 sur les surfaces des \u00e9quipements.<\/p>\n\n\n\n<p class=\"gb-text\">9. Nettoyage, remise \u00e0 neuf, etc. de supports hydrauliques miniers.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-4bdcfc5d\">\n<div>\n<h2 class=\"gb-text gb-text-27ac96d1\">Sp\u00e9cification d\u00e9taill\u00e9e du produit<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Mod\u00e8les<\/td><td>D\u00e9bit\uff08m\u00b3\/h\uff09<\/td><td>D\u00e9bit nominal (l\/min)<\/td><td>Pression nominale (Bar)<\/td><td>Puissance \uff08kw\uff09<\/td><td>Puissance du moteur diesel\uff08kw\uff09<\/td><td>Puissance du moteur \u00e0 essence\uff08HP\uff09<\/td><\/tr><tr><td>JMT-1<\/td><td>3.3<\/td><td>55<\/td><td>180<\/td><td>15KW<\/td><td>28HP<\/td><td>27HP<\/td><\/tr><tr><td>Jmt-2<\/td><td>4.8<\/td><td>80<\/td><td>180<\/td><td>22kw<\/td><td>33KW<\/td><td>37HP<\/td><\/tr><tr><td>JMT-2<\/td><td>7.2<\/td><td>135<\/td><td>180<\/td><td>37kw<\/td><td>62kw<\/td><td>&nbsp;<\/td><\/tr><tr><td>JMT-2<\/td><td>10.2<\/td><td>170<\/td><td>280<\/td><td>90kw<\/td><td>145w<\/td><td>&nbsp;<\/td><\/tr><tr><td>JMT-2<\/td><td>12.9<\/td><td>215<\/td><td>220<\/td><td>90kw<\/td><td>145kw<\/td><td>&nbsp;<\/td><\/tr><tr><td>JMT-2<\/td><td>15<\/td><td>250<\/td><td>200<\/td><td>90kw<\/td><td>145kw<\/td><td>&nbsp;<\/td><\/tr><tr><td>JMT-7<\/td><td>21<\/td><td>350<\/td><td>300<\/td><td>200kw<\/td><td>264kw<\/td><td>&nbsp;<\/td><\/tr><tr><td>JMT-7<\/td><td>28.8<\/td><td>480<\/td><td>200<\/td><td>200kw<\/td><td>264kw<\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-b0a8c443\">\n<div>\n<h2 class=\"gb-text gb-text-3e5a6473\"> Cas d'application<\/h2>\n\n\n\n<div class=\"gb-element-47fc66a8\">\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-607d0539\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5.jpg\" title=\"application du nettoyeur haute pression1\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application1-5-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-da2ebe66\"><strong>Nettoyage des tuyaux de ciment<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-726ec094\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4.jpg\" title=\"application du nettoyeur haute pression2\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application2-4-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-59f588a6\"><strong>Nettoyage des conduites d'\u00e9gout<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"960\" class=\"gb-media-1d9bdcdb\" alt=\"\" src=\"http:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4.jpg\" title=\"application du nettoyeur haute pression3\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4.jpg 853w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-267x300.jpg 267w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-768x864.jpg 768w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/high-pressure-cleaner-application3-4-11x12.jpg 11w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\n\n\n\n<p class=\"gb-text gb-text-ce832980\"><strong>Nettoyage de tranch\u00e9es carr\u00e9es<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8c8de760\">\n<div class=\"gb-element-fc1e320d\">\n<div>\n<h2 class=\"gb-text gb-text-8163a5d9\">Produits en vente directe<\/h2>\n\n\n<div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-345\" style=\"--carousel-slider-nav-color:rgb(30,115,190);--carousel-slider-active-nav-color:rgba(0,137,225,0.82);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-345\" class=\"carousel-slider carousel-slider-345 arrows-visibility-hover dots-visibility-always arrows-outside dots-center dots-square owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":true,\"slideBy\":4,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":4000,\"autoplaySpeed\":5000,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":3},\"576\":{\"items\":4},\"768\":{\"items\":4},\"1024\":{\"items\":4},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-presure-water-jet-cutting-machine\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Pressure-water-jet-cutting-machine-1.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Machine de d\u00e9coupe au jet d'eau\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-cooling-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/high-pressure-cooling-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Pompe \u00e0 eau de refroidissement \u00e0 haute pression\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-pipe-dredging-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/sewer-drain-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Nettoyeur de canalisations d'\u00e9gout \u00e0 haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-water-accessory-actuator\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Accessory-Actuator-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Actionneur d'accessoires<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-concrete-roughening-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/JMT-1-500bar-pressure-Cleaner.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Machine \u00e0 d\u00e9grossir le b\u00e9ton \u00e0 haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-test-pump-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-test-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Pompe d'essai \u00e0 haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-water-road-marking-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/\u56fe\u72471-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Mat\u00e9riel d'enl\u00e8vement des marquages routiers\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/hot-water-high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/250bar-hot-water-high-pressure-cleaner-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u00c9quipement de nettoyage \u00e0 haute pression \u00e0 l'eau chaude\n<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/automatic-high-pressure-cleaning-system\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Automatic-cleaning-system-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Syst\u00e8me de nettoyage automatique<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-cleaning-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/high-pressure-cleaning-equipment-1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Nettoyeurs \u00e0 haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/high-pressure-plunger-water-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump-300x225.jpg 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/Spunlace-nonwoven-pump.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Pompe \u00e0 eau \u00e0 piston haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/airport-runway-glue-removal-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/09\/Airport-runway-glue-removal-machine-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">https:\/\/jmtpressurejet.com\/airport-runway-glue-removal-equipment\/<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/jmt-2-high-pressure-grouting-pump\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/07\/High-pressure-jet-grouting-pump_\u526f\u672c-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-srcset=\"\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">Machine d'injection \u00e0 haute pression<\/p><\/div><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/jmtpressurejet.com\/fr\/water-jet-cutting-and-blasting-equipment\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-300x225.png 300w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-16x12.png 16w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1.png 640w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-620x464.png 620w, https:\/\/jmtpressurejet.com\/wp-content\/uploads\/2025\/08\/Water-Jet-Cutting-and-Blasting-Equipment1-400x299.png 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><div class=\"carousel-slider__caption\"><p class=\"caption\">\u00c9quipement de d\u00e9coupe et de sablage au jet d'eau\n<\/p><\/div><\/a><\/div>\n\n<\/div><!-- .carousel-slider-345 -->\n<\/div><!-- .carousel-slider-outer-345 -->\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-279faa38\">\n<div>\n<div class=\"gb-element-f30a2a07\">\n<div>\n<h2 class=\"gb-text gb-text-90c18544\">Prenez contact avec nous<\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"7\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/784#wpcf7-f7-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/pages\/784#wpcf7-f7-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Courriel*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"T\u00e9l\u00e9phone*\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Quelques conseils pour un devis rapide et pr\u00e9cis* : 1. Quel \u00e9quipement devez-vous acheter ? 2. Quelle est votre application\/industrie principale ? 3. Quelle est votre exigence en mati\u00e8re de pression\/d\u00e9bit ?\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Soumettre\" \/>\n<\/p><input type=\"hidden\" id=\"ct_checkjs_cf7_5e9f92a01c986bafcabbafd145520b13\" name=\"ct_checkjs_cf7\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_cf7_5e9f92a01c986bafcabbafd145520b13\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, '1499353dbb4dcd643962149a0691e276cd27b79cebd88e665d0884a7f539b423');}}, 1000);<\/script><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>JMT-1-180BAR Motor Sewer Drain Cleaning Machine Model JMT-1 Outlet Pressure 180bar\/2600psi Water Flow Rate 55L\/min Plunger Diameter 28mm Number of Plungers 3 Input Speed 3600r\/min Pump Speed 1450r\/min Plunger Stroke 21mm Motor Power 15KW Water Inlet Size 1.5-inch Working Principles The high-pressure pump generates a high-pressure water jet. Connect the pipe unclogging nozzle to the &#8230; <a title=\"JMT-1-180BAR motor driven pipe dredging machine\" class=\"read-more\" href=\"https:\/\/jmtpressurejet.com\/fr\/jmt-1-180bar-motor-driven-pipe-dredging-machine\/\" aria-label=\"En savoir plus sur JMT-1-180BAR motor driven pipe dredging machine\">Lire plus<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-784","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/pages\/784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/comments?post=784"}],"version-history":[{"count":5,"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/pages\/784\/revisions"}],"predecessor-version":[{"id":1468,"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/pages\/784\/revisions\/1468"}],"wp:attachment":[{"href":"https:\/\/jmtpressurejet.com\/fr\/wp-json\/wp\/v2\/media?parent=784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}